{"id":3,"date":"2019-08-13T13:06:06","date_gmt":"2019-08-13T13:06:06","guid":{"rendered":"https:\/\/dev.doozy.it\/otticacarraro\/?page_id=3"},"modified":"2026-01-27T09:59:37","modified_gmt":"2026-01-27T08:59:37","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document privacy-statement cmplz-document-eu\"><p><i>Questa dichiarazione sulla privacy \u00e8 stata aggiornata l'ultima volta il 27\/01\/2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.<\/i><br \/><br \/><\/p><p><p>In questa dichiarazione sulla privacy, spieghiamo cosa facciamo con i tuoi dati che otteniamo attraverso <a href=\"https:\/\/www.otticacarraro.it\/it\/\">https:\/\/www.otticacarraro.it\/it\/<\/a>. Ti consigliamo di leggere attentamente la dichiarazione. Durante l'elaborazione rispettiamo i requisiti della legislazione sulla privacy. Ci\u00f2 significa, tra le altre cose, che:<\/p><ul>\n                <li>comunichiamo chiaramente il motivo per il quale processiamo dati personali. Facciamo questo per mezzo di questa dichiarazione sulla privacy;<\/li>\n                <li>miriamo a limitare la raccolta di dati personali solo ai dati personali richiesti per scopi legittimi;<\/li>\n                <li>prima chiediamo il tuo esplicito consenso per processare i tuoi dati personali nei casi che richiedono il tuo consenso;<\/li>\n                <li>adottiamo misure di sicurezza appropriate per proteggere i tuoi dati personali e lo richiediamo anche da parti che elaborano dati personali per nostro conto;<\/li>\n                <li>rispettiamo il tuo diritto di accesso ai tuoi dati personali o di averli corretti o cancellati, su tua richiesta.<\/li>\n            <\/ul><p>Se hai domande o vuoi sapere esattamente quali dati conserviamo, contattaci.<\/p><\/p><h2>1. Scopo, dati e periodo di conservazione<\/h2>Possiamo raccogliere o ricevere informazioni personali per una serie di scopi legati alle nostre operazioni commerciali che possono includere quanto segue: (clicca per espandere)<details class=\"cmplz-dropdown dropdown-privacy-statement\"><summary><div><h3>1.1 Contatto - Tramite telefono, posta, email e\/o moduli web<\/h3><\/div><\/summary><p class=\"cmplz-subtitle\">Per questo scopo usiamo i seguenti dati:<\/p><p><ul><li>Un nome e cognome<\/li><li>Un indirizzo email<\/li><li>Un numero di telefono<\/li><\/ul><\/p><p class=\"cmplz-subtitle\">La base con la quale processiamo i dati \u00e8:<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/legal-bases\/#consent\">Su disposizione del consenso.<\/a><\/p><p class=\"cmplz-subtitle\">Periodo di conservazione<\/p><p>Conserviamo questi dati fino al termine del servizio.<\/p><\/details><details class=\"cmplz-dropdown dropdown-privacy-statement\"><summary><div><h3>1.2 Pagamenti<\/h3><\/div><\/summary><p class=\"cmplz-subtitle\">Per questo scopo usiamo i seguenti dati:<\/p><p><ul><li>Un nome e cognome<\/li><li>Dati geolocalizzazione<\/li><li>Una casa oppure un differente indirizzo fisico, incluso nome della via e citt\u00e0<\/li><li>Un numero di telefono<\/li><li>Un indirizzo email<\/li><\/ul><\/p><p class=\"cmplz-subtitle\">La base con la quale processiamo i dati \u00e8:<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/legal-bases\/#consent\">Su disposizione del consenso.<\/a><\/p><p class=\"cmplz-subtitle\">Periodo di conservazione<\/p><p>Conserviamo questi dati fino al termine del servizio.<\/p><\/details><h2>2. Cookie<\/h2><p>Il nostro sito web usa cookie. Per ulteriori informazioni riguardo i cookie, per favore fai riferimento alla nostra <a href=\"https:\/\/www.otticacarraro.it\/it\/cookie-policy\/\">Cookie Policy<\/a>.&nbsp;<\/p><h2>3. Pratiche di divulgazione<\/h2><p><p>Comunichiamo informazioni personali se ci viene richiesto dalla legge o da un ordine del tribunale, in risposta a un'autorit\u00e0 incaricata dell'applicazione della legge, nella misura consentita da altre disposizioni di legge, per fornire informazioni o per un'indagine su una questione relativa alla sicurezza pubblica.<\/p><p>Se il nostro sito Web o organizzazione viene rilevato, venduto o coinvolto in una fusione o acquisizione, i tuoi dati potrebbero essere divulgati ai nostri consulenti e a eventuali potenziali acquirenti e saranno trasmessi ai nuovi proprietari.<\/p><\/p><p>Abbiamo concluso un accordo di elaborazione dei dati con Google.<\/p><p>Google non pu\u00f2 utilizzare i dati per altri servizi di Google.<\/p><h2>4. Sicurezza<\/h2><p>Ci impegniamo per la sicurezza dei dati personali. Prendiamo adeguate misure di sicurezza per limitare l'abuso e l'accesso non autorizzato ai dati personali. Ci\u00f2 garantisce che solo le persone necessarie abbiano accesso ai tuoi dati, che l'accesso ai dati sia protetto e che le nostre misure di sicurezza vengano regolarmente riviste.<\/p><p>Le misure di sicurezza che usiamo consistono in:<\/p><p><ul><li>Sicurezza d&#039;Accesso<\/li><li>DKIM, SPF, DMARC e altre impostazioni DNS specifiche<\/li><li>Crittografia (START)TLS \/ SSL \/ DANE<\/li><li>HTTP Strict Transport Security e relative intestazioni di sicurezza e politiche del browser<\/li><li>Hardening Sito\/Funzioni di Sicurezza<\/li><li>Rilevamento vulnerabilit\u00e0<\/li><\/ul><\/p><h2>5. Siti web di terze parti<\/h2><p>Questa dichiarazione sulla privacy non si applica ai siti web di terzi collegati tramite link sul nostro sito web. Non possiamo garantire che queste terze parti gestiscano i vostri dati personali in modo affidabile e sicuro. Vi consigliamo di leggere le dichiarazioni sulla privacy di questi siti web prima di utilizzarli.<\/p><h2>6. Ammende riguardo questa dichiarazione della privacy<\/h2><p>Ci riserviamo il diritto di apportare modifiche alla presente dichiarazione sulla privacy. Si raccomanda di consultare regolarmente questa dichiarazione sulla privacy per essere a conoscenza di eventuali modifiche. Inoltre, ti informeremo attivamente laddove possibile.<\/p><h2>7. Accesso e modifica dei tuoi dati<\/h2><p>Se hai domande o vuoi sapere esattamente quali tuoi dati sono in nostro possesso, contattaci. Potrai contattarci usando le informazioni presenti qui sotto. Hai i seguenti diritti:<\/p><ul>\n                <li>Hai il diritto di sapere quando i tuoi dati personali sono necessari, cosa succede ad essi, quanto a lungo verranno mantenuti.<\/li>\n                <li>Diritto di accesso: hai il diritto ad accedere ai tuoi dati personali dei quali siamo a conoscenza.<\/li>\n                <li>Diritto di rettifica: hai il diritto di completare, correggere, cancellare o bloccare i tuoi dati personali quando lo desideri.<\/li>\n                <li>Se hai domande o problemi relativi al accessibilit\u00e0 del sito web, per favore non esitare a contattarci.<\/li>\n                <li>Diritto di trasferire i tuoi dati: hai il diritto di richiedere tutti i tuoi dati dal controllore e trasferirli tutti quanti ad un altro controllore.<\/li>\n                <li>Diritto di obiezione: hai il diritto di obiezione verso il processo dei tuoi dati. Noi rispetteremo questa scelta, a meno che non ci siano delle basi valide per il processo.<\/li>\n            <\/ul><p>Assicurati di segnalare sempre in modo chiaro chi sei, cos\u00ec da essere certi di non cancellare o modificare i dati di un una persona sbagliata.<\/p><h2>8. Invio di un reclamo<\/h2><p>Se non sei soddisfatto di come gestiamo (una lamentela su) il processo dei tuoi dati personali, hai il diritto di spedire un reclamo al Garante per la protezione dei dati personali.<\/p><h2>9. Dettagli contatti<\/h2><p>Ottica Carraro<br \/>\n        Calle della Mandola<br \/>\nSan Marco 3706 - Venezia (Italy)<br \/>\n        Stati Uniti<br \/>\n        Sito web: <a href=\"https:\/\/www.otticacarraro.it\/it\/\">https:\/\/www.otticacarraro.it\/it\/<\/a> <br \/>\n        Email: <span class=\"cmplz-obfuscate\">ca&#114;&#114;&#097;&#114;&#111;@<span class=\"cmplz-fmail-domain\">&#101;&#120;&#046;com<\/span>&#111;&#116;&#116;icacar&#114;&#097;&#114;&#111;.&#105;t<\/span> <br \/>\n        <\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Questa dichiarazione sulla privacy \u00e8 stata aggiornata l&#8217;ultima volta il 27\/01\/2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.In questa dichiarazione sulla privacy, spieghiamo cosa facciamo con i tuoi dati che otteniamo attraverso https:\/\/www.otticacarraro.it\/it\/. Ti consigliamo di leggere attentamente la dichiarazione. Durante l&#8217;elaborazione rispettiamo i requisiti&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy Policy | Ottica Carraro Eyeweardesign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy | Ottica Carraro Eyeweardesign\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Ottica Carraro Eyeweardesign\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/carraroEyeweardesign\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T08:59:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/\",\"url\":\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/\",\"name\":\"Privacy Policy | Ottica Carraro Eyeweardesign\",\"isPartOf\":{\"@id\":\"https:\/\/www.otticacarraro.it\/it\/#website\"},\"datePublished\":\"2019-08-13T13:06:06+00:00\",\"dateModified\":\"2026-01-27T08:59:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.otticacarraro.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.otticacarraro.it\/it\/#website\",\"url\":\"https:\/\/www.otticacarraro.it\/it\/\",\"name\":\"Ottica Carraro Eyeweardesign\",\"description\":\"Negozio di occhiali a Venezia\",\"publisher\":{\"@id\":\"https:\/\/www.otticacarraro.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.otticacarraro.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.otticacarraro.it\/it\/#organization\",\"name\":\"Ottica Carraro\",\"url\":\"https:\/\/www.otticacarraro.it\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.otticacarraro.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.otticacarraro.it\/wp-content\/uploads\/2019\/08\/logo_ottica_carraro_hd.png\",\"contentUrl\":\"https:\/\/www.otticacarraro.it\/wp-content\/uploads\/2019\/08\/logo_ottica_carraro_hd.png\",\"width\":800,\"height\":142,\"caption\":\"Ottica Carraro\"},\"image\":{\"@id\":\"https:\/\/www.otticacarraro.it\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/carraroEyeweardesign\/\",\"https:\/\/www.instagram.com\/explore\/tags\/otticacarraro\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy | Ottica Carraro Eyeweardesign","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy Policy | Ottica Carraro Eyeweardesign","og_url":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/","og_site_name":"Ottica Carraro Eyeweardesign","article_publisher":"https:\/\/www.facebook.com\/carraroEyeweardesign\/","article_modified_time":"2026-01-27T08:59:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/","url":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/","name":"Privacy Policy | Ottica Carraro Eyeweardesign","isPartOf":{"@id":"https:\/\/www.otticacarraro.it\/it\/#website"},"datePublished":"2019-08-13T13:06:06+00:00","dateModified":"2026-01-27T08:59:37+00:00","breadcrumb":{"@id":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.otticacarraro.it\/it\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.otticacarraro.it\/it\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.otticacarraro.it\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.otticacarraro.it\/it\/#website","url":"https:\/\/www.otticacarraro.it\/it\/","name":"Ottica Carraro Eyeweardesign","description":"Negozio di occhiali a Venezia","publisher":{"@id":"https:\/\/www.otticacarraro.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.otticacarraro.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.otticacarraro.it\/it\/#organization","name":"Ottica Carraro","url":"https:\/\/www.otticacarraro.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.otticacarraro.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.otticacarraro.it\/wp-content\/uploads\/2019\/08\/logo_ottica_carraro_hd.png","contentUrl":"https:\/\/www.otticacarraro.it\/wp-content\/uploads\/2019\/08\/logo_ottica_carraro_hd.png","width":800,"height":142,"caption":"Ottica Carraro"},"image":{"@id":"https:\/\/www.otticacarraro.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/carraroEyeweardesign\/","https:\/\/www.instagram.com\/explore\/tags\/otticacarraro"]}]}},"_links":{"self":[{"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.otticacarraro.it\/it\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}